{"id":47,"count":103,"description":"","link":"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/","name":"diamond saw blades","slug":"diamond-saw-blades","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>diamond saw blades Archives - Diamond Blade Portal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"diamond saw blades Archives - Diamond Blade Portal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/\" \/>\n<meta property=\"og:site_name\" content=\"Diamond Blade Portal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@diamondkingtool\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/tag\\\/diamond-saw-blades\\\/\",\"url\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/tag\\\/diamond-saw-blades\\\/\",\"name\":\"diamond saw blades Archives - Diamond Blade Portal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/tag\\\/diamond-saw-blades\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/tag\\\/diamond-saw-blades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"diamond saw blades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/\",\"name\":\"Diamond Blade Portal\",\"description\":\"Best Diamond Blades On The Planet\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/#organization\",\"name\":\"Diamond King Tools\",\"url\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/favicon-logo.png\",\"contentUrl\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/favicon-logo.png\",\"width\":104,\"height\":123,\"caption\":\"Diamond King Tools\"},\"image\":{\"@id\":\"https:\\\/\\\/diamondkingtools.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diamondkingtools\\\/\",\"https:\\\/\\\/x.com\\\/diamondkingtool\",\"https:\\\/\\\/www.instagram.com\\\/diamondkingtools\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"diamond saw blades Archives - Diamond Blade Portal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/","og_locale":"en_US","og_type":"article","og_title":"diamond saw blades Archives - Diamond Blade Portal","og_url":"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/","og_site_name":"Diamond Blade Portal","twitter_card":"summary_large_image","twitter_site":"@diamondkingtool","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/","url":"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/","name":"diamond saw blades Archives - Diamond Blade Portal","isPartOf":{"@id":"https:\/\/diamondkingtools.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/diamondkingtools.com\/blog\/tag\/diamond-saw-blades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diamondkingtools.com\/blog\/"},{"@type":"ListItem","position":2,"name":"diamond saw blades"}]},{"@type":"WebSite","@id":"https:\/\/diamondkingtools.com\/blog\/#website","url":"https:\/\/diamondkingtools.com\/blog\/","name":"Diamond Blade Portal","description":"Best Diamond Blades On The Planet","publisher":{"@id":"https:\/\/diamondkingtools.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diamondkingtools.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/diamondkingtools.com\/blog\/#organization","name":"Diamond King Tools","url":"https:\/\/diamondkingtools.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/diamondkingtools.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/diamondkingtools.com\/blog\/wp-content\/uploads\/2021\/09\/favicon-logo.png","contentUrl":"https:\/\/diamondkingtools.com\/blog\/wp-content\/uploads\/2021\/09\/favicon-logo.png","width":104,"height":123,"caption":"Diamond King Tools"},"image":{"@id":"https:\/\/diamondkingtools.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diamondkingtools\/","https:\/\/x.com\/diamondkingtool","https:\/\/www.instagram.com\/diamondkingtools\/"]}]}},"_links":{"self":[{"href":"https:\/\/diamondkingtools.com\/blog\/wp-json\/wp\/v2\/tags\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamondkingtools.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/diamondkingtools.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/diamondkingtools.com\/blog\/wp-json\/wp\/v2\/posts?tags=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}